{"id":990156,"date":"2021-06-05T17:17:06","date_gmt":"2021-06-05T17:17:06","guid":{"rendered":"https:\/\/jcmm16.org\/privacy-policy"},"modified":"2021-10-21T06:23:13","modified_gmt":"2021-10-21T06:23:13","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/jcmm16.org\/fr\/privacy-policy","title":{"rendered":"Privacy Policy"},"content":{"rendered":"<div class=\"row \"><div class=\"wpv-grid grid-1-1  wpv-first-level first unextended\" style=\"padding-top:0px;padding-bottom:0px\" id=\"wpv-column-15e131b355fed08458aa271533787a44\" ><h1 style=\"text-align: center;\">Mentions l\u00e9gales et politique de confidentialit\u00e9<\/h1>\n<p><strong> <\/strong><\/p>\n<p>L&rsquo;association Jesus Church Mission Mark 16, soucieuse des droits des individus, notamment au regard des traitements automatis\u00e9s et dans une volont\u00e9 de transparence avec ses clients, a mis en place une politique reprenant l\u2019ensemble de ces traitements, des finalit\u00e9s poursuivies par ces derniers ainsi que des moyens d\u2019actions \u00e0 la disposition des individus afin qu\u2019ils puissent au mieux exercer leurs droits.<\/p>\n<p>Pour toute information compl\u00e9mentaire sur la protection des donn\u00e9es personnelles, nous vous invitons \u00e0 consulter le site : https:\/\/www.cnil.fr\/<a href=\"https:\/\/www.cnil.fr\/\"><\/a><\/p>\n<p>La poursuite de la navigation sur ce site vaut acceptation sans r\u00e9serve des dispositions et conditions d&rsquo;utilisation qui suivent.<\/p>\n<p>La version actuellement en ligne de ces conditions d&rsquo;utilisation est la seule opposable pendant toute la dur\u00e9e d&rsquo;utilisation du site et jusqu&rsquo;\u00e0 ce qu&rsquo;une nouvelle version la remplace.<\/p>\n<h1>Article 1 &#8211; Mentions l\u00e9gales<\/h1>\n<p><strong> <\/strong><\/p>\n<ul>\n<li><u>Site (ci-apr\u00e8s \u00ab le<\/u> Site \u00bb) :<\/li>\n<\/ul>\n<p>JCMM16<\/p>\n<ul>\n<li><u>Editeur (ci-apr\u00e8s \u00ab l&rsquo;<\/u> Editeur \u00bb) :<\/li>\n<\/ul>\n<p>L&rsquo;association Jesus Church Mission Mark 16, d\u00e9clar\u00e9e aupr\u00e8s de la pr\u00e9fecture de sous le num\u00e9ro<\/p>\n<p>dont le si\u00e8ge social est situ\u00e9 : 7900 Central Avenue &#8211; Hyattsville MD 20785 n\u00b0 de t\u00e9l\u00e9phone : 3012452000<\/p>\n<p>adresse mail <a href=\"mailto:jesuschurch@live.com\">: jesuschurch@live.com<\/a> repr\u00e9sent\u00e9 par Kob BILEY, Fondateur<\/p>\n<ul>\n<li><u>H\u00f4te (ci-apr\u00e8s \u00ab l&rsquo;<\/u> H\u00f4te \u00bb):<\/li>\n<\/ul>\n<p>JCMM16 est h\u00e9berg\u00e9 par IONOS, dont le si\u00e8ge social est situ\u00e9 7 Place de La Gare 57200 SARREGUEMINES.<\/p>\n<h1>Article 2 &#8211; Acc\u00e8s au site<\/h1>\n<p><strong> <\/strong><\/p>\n<p>L&rsquo;acc\u00e8s au site et son utilisation sont r\u00e9serv\u00e9s \u00e0 un usage strictement personnel. Vous vous engagez \u00e0 ne pas utiliser ce site et les informations ou donn\u00e9es qui y figurent \u00e0 des fins commerciales, politiques, publicitaires et pour toute forme de sollicitation commerciale et notamment l&rsquo;envoi de courriers \u00e9lectroniques non sollicit\u00e9s.<\/p>\n<h1>Article 3 &#8211; Contenu du site<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Toutes les marques, photographies, textes, commentaires, illustrations, images anim\u00e9es ou non, s\u00e9quences vid\u00e9o, sons, ainsi que toutes les applications informatiques qui pourraient \u00eatre utilis\u00e9es pour faire fonctionner ce site et<\/p>\n<p>plus g\u00e9n\u00e9ralement tous les \u00e9l\u00e9ments reproduits ou utilis\u00e9s sur le site sont prot\u00e9g\u00e9s par les lois en vigueur au titre de la propri\u00e9t\u00e9 intellectuelle.<\/p>\n<p>Ils sont la propri\u00e9t\u00e9 pleine et enti\u00e8re de l&rsquo;\u00e9diteur ou de ses partenaires. Toute reproduction, repr\u00e9sentation, utilisation ou adaptation, sous quelque forme que ce soit, de tout ou partie de ces \u00e9l\u00e9ments, y compris les applications informatiques, sans l&rsquo;accord pr\u00e9alable et \u00e9crit de l&rsquo;\u00e9diteur, sont strictement interdites. Le fait pour l&rsquo;\u00e9diteur de ne pas engager de proc\u00e9dure d\u00e8s la prise de connaissance de ces utilisations non autoris\u00e9es ne vaut pas acceptation desdites utilisations et renonciation aux poursuites. The fact that the publisher does not initiate proceedings as soon as it becomes aware of these unauthorized uses does not constitute acceptance of said uses and waiver of prosecution.<\/p>\n<h1>Article 4 &#8211; Gestion du site<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Pour la bonne gestion du site, l&rsquo;\u00e9diteur pourra \u00e0 tout moment :<\/p>\n<ul>\n<li>&#8211; suspendre, interrompre ou limiter l&rsquo;acc\u00e8s \u00e0 tout ou partie du site, r\u00e9server l&rsquo;acc\u00e8s au site, ou \u00e0 certaines parties du site, \u00e0 une cat\u00e9gorie d\u00e9termin\u00e9e d&rsquo;internautes ;<\/li>\n<li>&#8211; supprimer toute information pouvant en perturber le fonctionnement ou entrant en contravention avec les lois nationales ou internationales ;<\/li>\n<li>&#8211; suspendre le site afin de proc\u00e9der \u00e0 des mises \u00e0 jour.<\/li>\n<\/ul>\n<h1>Article 5 &#8211; Responsabilit\u00e9s<\/h1>\n<p><strong> <\/strong><\/p>\n<p>La responsabilit\u00e9 de l&rsquo;\u00e9diteur ne peut \u00eatre engag\u00e9e en cas de d\u00e9faillance, panne, difficult\u00e9 ou interruption de fonctionnement, emp\u00eachant l&rsquo;acc\u00e8s au site ou \u00e0 une de ses fonctionnalit\u00e9s.<\/p>\n<p>Le mat\u00e9riel de connexion au site que vous utilisez est sous votre enti\u00e8re responsabilit\u00e9. Vous devez prendre toutes les mesures appropri\u00e9es pour prot\u00e9ger votre mat\u00e9riel et vos propres donn\u00e9es notamment d&rsquo;attaques virales par Internet. Vous \u00eates par ailleurs seul responsable des sites et donn\u00e9es que vous consultez.<\/p>\n<p>Vous \u00eates par ailleurs seul responsable des sites et donn\u00e9es que vous consultez.<\/p>\n<ul>\n<li>&#8211; du fait de l&rsquo;usage du site ou de tout service accessible via Internet ;<\/li>\n<li>&#8211; du fait du non-respect par vous des pr\u00e9sentes conditions g\u00e9n\u00e9rales.<\/li>\n<\/ul>\n<p>L&rsquo;\u00e9diteur n&rsquo;est pas responsable des dommages caus\u00e9s \u00e0 vous, \u00e0 des tiers et\/ou \u00e0 votre mat\u00e9riel du fait de votre connexion ou utilisation du site et vous renoncez \u00e0 toute action \u00e0 son encontre de ce fait.<\/p>\n<p>Si l&rsquo;\u00e9diteur devait faire l&rsquo;objet d&rsquo;une proc\u00e9dure amiable ou judiciaire du fait de votre utilisation du site, il pourra se retourner contre vous pour obtenir r\u00e9paration de tous dommages, sommes, condamnations et frais qui pourraient d\u00e9couler de cette proc\u00e9dure.<\/p>\n<h1>Article 6 &#8211; Liens hypertextes<\/h1>\n<p><strong> <\/strong><\/p>\n<p>La mise en place par les utilisateurs de tous liens hypertextes vers tout ou partie du site est strictement interdite, sauf autorisation pr\u00e9alable et \u00e9crite de l&rsquo;\u00e9diteur.<\/p>\n<p>L&rsquo;\u00e9diteur est libre de refuser cette autorisation sans avoir \u00e0 justifier de quelque mani\u00e8re que ce soit sa d\u00e9cision. Dans le cas o\u00f9 l&rsquo;\u00e9diteur accorderait son autorisation, celle-ci n&rsquo;est dans tous les cas que temporaire et pourra \u00eatre retir\u00e9e \u00e0 tout moment, sans obligation de justification \u00e0 la charge de l&rsquo;\u00e9diteur.<\/p>\n<p>Toute information accessible via un lien vers d&rsquo;autres sites n&rsquo;est pas publi\u00e9e par l&rsquo;\u00e9diteur. L&rsquo;\u00e9diteur ne dispose d&rsquo;aucun droit sur le contenu pr\u00e9sent dans ledit lien.<\/p>\n<h1>L&rsquo;\u00e9diteur ne dispose d&rsquo;aucun droit sur le contenu pr\u00e9sent dans ledit lien.<\/h1>\n<p>Vos donn\u00e9es sont collect\u00e9es par l&rsquo;association Jesus Church Mission Mark 16.<\/p>\n<p>Une donn\u00e9e \u00e0 caract\u00e8re personnel d\u00e9signe toute information concernant une personne physique identifi\u00e9e ou identifiable (personne concern\u00e9e) ; est r\u00e9put\u00e9e identifiable une personne qui peut \u00eatre identifi\u00e9e, directement ou indirectement, notamment par r\u00e9f\u00e9rence \u00e0 un nom, un num\u00e9ro d&rsquo;identification ou \u00e0 un ou plusieurs \u00e9l\u00e9ments sp\u00e9cifiques, propres \u00e0 son identit\u00e9 physique, physiologique, g\u00e9n\u00e9tique, psychique, \u00e9conomique, culturelle ou sociale.<\/p>\n<p>Les informations personnelles pouvant \u00eatre recueillies sur le site sont principalement utilis\u00e9es par l&rsquo;\u00e9diteur pour la gestion des relations avec vous, et le cas \u00e9ch\u00e9ant pour le traitement de vos commandes.<\/p>\n<p>Les donn\u00e9es personnelles collect\u00e9es sont les suivantes :<\/p>\n<p>&#8211;<\/p>\n<ul>\n<li>&#8211; donn\u00e9es financi\u00e8res : dans le cadre du paiement des produits et prestations propos\u00e9s sur la Plateforme, celle-ci enregistre des donn\u00e9es financi\u00e8res relatives \u00e0 la carte de cr\u00e9dit de l&rsquo;utilisateur.<\/li>\n<\/ul>\n<h1>Article 8 &#8211; Droit d\u2019acc\u00e8s, de rectification et de d\u00e9r\u00e9f\u00e9rencement de vos donn\u00e9es<\/h1>\n<p><strong> <\/strong><\/p>\n<p>En application de la r\u00e9glementation applicable aux donn\u00e9es \u00e0 caract\u00e8re personnel, les utilisateurs disposent des droits suivants :<\/p>\n<ul>\n<li>\u2022 le droit d\u2019acc\u00e8s : ils peuvent exercer leur droit d&rsquo;acc\u00e8s, pour conna\u00eetre les donn\u00e9es personnelles les concernant, en \u00e9crivant \u00e0 l&rsquo;adresse \u00e9lectronique ci-dessous mentionn\u00e9e. Dans ce cas, avant la mise en \u0153uvre de ce droit, la Plateforme peut demander une preuve de l&rsquo;identit\u00e9 de l&rsquo;utilisateur afin d&rsquo;en v\u00e9rifier l&rsquo;exactitude ; \u2022 le droit de rectification : si les donn\u00e9es \u00e0 caract\u00e8re personnel d\u00e9tenues par la Plateforme sont inexactes, ils peuvent demander la mise \u00e0 jour des informations ;<\/li>\n<li>\u2022 le droit de suppression des donn\u00e9es : les utilisateurs peuvent demander la suppression de leurs donn\u00e9es \u00e0 caract\u00e8re personnel, conform\u00e9ment aux lois applicables en mati\u00e8re de protection des donn\u00e9es ;<\/li>\n<li>le droit \u00e0 l&rsquo;effacement des donn\u00e9es : les utilisateurs peuvent demander la suppression de leurs donn\u00e9es personnelles, conform\u00e9ment aux lois applicables en mati\u00e8re de protection des donn\u00e9es ;<\/li>\n<li>\u2022 le droit \u00e0 la limitation du traitement : les utilisateurs peuvent de demander \u00e0 la Plateforme de limiter le traitement des donn\u00e9es personnelles conform\u00e9ment aux hypoth\u00e8ses pr\u00e9vues par le RGPD ;<\/li>\n<li>\u2022 le droit de s\u2019opposer au traitement des donn\u00e9es : les utilisateurs peuvent s\u2019opposer \u00e0 ce que leurs donn\u00e9es soient trait\u00e9es conform\u00e9ment aux hypoth\u00e8ses pr\u00e9vues par le RGPD ;<\/li>\n<li>\u2022 le droit \u00e0 la portabilit\u00e9 : ils peuvent r\u00e9clamer que la Plateforme leur remette les donn\u00e9es personnelles qu&rsquo;ils ont fournies pour les transmettre \u00e0 une nouvelle Plateforme.<\/li>\n<\/ul>\n<p>Vous pouvez exercer ce droit en nous contactant, \u00e0 l\u2019adresse suivante :<\/p>\n<p>7900 Central Avenue &#8211; Hyattsville MD 20785 .<\/p>\n<p>Ou par email, \u00e0 l\u2019adresse :<\/p>\n<p>Toute demande doit \u00eatre accompagn\u00e9e de la photocopie d\u2019un titre d\u2019identit\u00e9 en cours de validit\u00e9 sign\u00e9 et faire mention de l\u2019adresse \u00e0 laquelle l&rsquo;\u00e9diteur pourra contacter le demandeur. La r\u00e9ponse sera adress\u00e9e dans le mois suivant la r\u00e9ception de la demande. Ce d\u00e9lai d&rsquo;un mois peut \u00eatre prolong\u00e9 de deux mois si la complexit\u00e9 de la demande et\/ou le nombre de demandes l&rsquo;exigent.<\/p>\n<p>De plus, et depuis la loi n\u00b02016-1321 du 7 octobre 2016, les personnes qui le souhaitent, ont la possibilit\u00e9 d\u2019organiser le sort de leurs donn\u00e9es apr\u00e8s leur d\u00e9c\u00e8s. Pour plus d\u2019information sur le sujet, vous pouvez consulter le site Internet de la CNIL : https:\/\/www.cnil.fr\/. <a href=\"http:\/\/www.cnil.fr\/\"><\/a><\/p>\n<p>Pour plus d\u2019information sur le sujet, vous pouvez consulter le site Internet de la CNIL : https:\/\/www.cnil.fr\/. <a href=\"https:\/\/www.cnil.fr\/\"><\/a><\/p>\n<p>Nous vous recommandons de nous contacter dans un premier temps avant de d\u00e9poser une r\u00e9clamation aupr\u00e8s de la CNIL, car nous sommes \u00e0 votre enti\u00e8re disposition pour r\u00e9gler votre probl\u00e8me.<\/p>\n<h1>Article 9 &#8211; Utilisation des donn\u00e9es<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Les donn\u00e9es personnelles collect\u00e9es aupr\u00e8s des utilisateurs ont pour objectif la mise \u00e0 disposition des services de la Plateforme, leur am\u00e9lioration et le maintien d&rsquo;un environnement s\u00e9curis\u00e9. La base l\u00e9gale des traitements est l\u2019ex\u00e9cution du contrat entre l\u2019utilisateur et la Plateforme. Plus pr\u00e9cis\u00e9ment, les utilisations sont les suivantes :<\/p>\n<ul>\n<li>&#8211; acc\u00e8s et utilisation de la Plateforme par l&rsquo;utilisateur ;<\/li>\n<li>&#8211; gestion du fonctionnement et optimisation de la Plateforme ;<\/li>\n<li>&#8211; mise en \u0153uvre d&rsquo;une assistance utilisateurs ;<\/li>\n<li>&#8211; v\u00e9rification, identification et authentification des donn\u00e9es transmises par l&rsquo;utilisateur ;<\/li>\n<li>&#8211; personnalisation des services en affichant des publicit\u00e9s en fonction de l&rsquo;historique de navigation de l&rsquo;utilisateur, selon ses pr\u00e9f\u00e9rences ;<\/li>\n<li>&#8211; pr\u00e9vention et d\u00e9tection des fraudes, malwares (malicious softwares ou logiciels malveillants) et gestion des incidents de s\u00e9curit\u00e9 ;<\/li>\n<li>&#8211; gestion des \u00e9ventuels litiges avec les utilisateurs ;<\/li>\n<li>&#8211; envoi d&rsquo;informations commerciales et publicitaires, en fonction des pr\u00e9f\u00e9rences de l&rsquo;utilisateur ;<\/li>\n<li>&#8211; organisation des conditions d&rsquo;utilisation des Services de paiement.<\/li>\n<\/ul>\n<h1>Article 10 &#8211; Politique de conservation des donn\u00e9es<\/h1>\n<p><strong> <\/strong><\/p>\n<p>La Plateforme conserve vos donn\u00e9es pour la dur\u00e9e n\u00e9cessaire pour vous fournir ses services ou son assistance.<\/p>\n<p>Dans la mesure raisonnablement n\u00e9cessaire ou requise pour satisfaire aux obligations l\u00e9gales ou r\u00e9glementaires, r\u00e9gler des litiges, emp\u00eacher les fraudes et abus ou appliquer nos modalit\u00e9s et conditions, nous pouvons \u00e9galement conserver certaines de vos informations si n\u00e9cessaire, m\u00eame apr\u00e8s que vous ayez ferm\u00e9 votre compte ou que nous n&rsquo;ayons plus besoin pour vous fournir nos services.<\/p>\n<h1>Article 11- Partage des donn\u00e9es personnelles avec des tiers<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Les donn\u00e9es personnelles peuvent \u00eatre partag\u00e9es avec des soci\u00e9t\u00e9s tierces exclusivement dans l\u2019Union europ\u00e9enne, dans les cas suivants :<\/p>\n<ul>\n<li>&#8211; quand l&rsquo;utilisateur utilise les services de paiement, pour la mise en \u0153uvre de ces services, la Plateforme est en relation avec des soci\u00e9t\u00e9s bancaires et financi\u00e8res tierces avec lesquelles elle a pass\u00e9 des contrats ;<\/li>\n<li>&#8211; lorsque l&rsquo;utilisateur publie, dans les zones de commentaires libres de la Plateforme, des informations accessibles au public ;<\/li>\n<li>&#8211; quand l&rsquo;utilisateur autorise le site web d&rsquo;un tiers \u00e0 acc\u00e9der \u00e0 ses donn\u00e9es ;<\/li>\n<li>&#8211; quand l&rsquo;utilisateur autorise le site web d&rsquo;un tiers \u00e0 acc\u00e9der \u00e0 ses donn\u00e9es ; &#8211; quand la Plateforme recourt aux services de prestataires pour fournir l&rsquo;assistance utilisateurs, la publicit\u00e9 et les services de paiement. Ces prestataires disposent d&rsquo;un acc\u00e8s limit\u00e9 aux donn\u00e9es de l&rsquo;utilisateur, dans le cadre de l&rsquo;ex\u00e9cution de ces prestations, et ont l&rsquo;obligation contractuelle de les utiliser en conformit\u00e9 avec les dispositions de la r\u00e9glementation applicable en mati\u00e8re protection des donn\u00e9es \u00e0 caract\u00e8re personnel ;<\/li>\n<li>&#8211; si la loi l&rsquo;exige, la Plateforme peut effectuer la transmission de donn\u00e9es pour donner suite aux r\u00e9clamations pr\u00e9sent\u00e9es contre la Plateforme et se conformer aux proc\u00e9dures administratives et judiciaires.<\/li>\n<\/ul>\n<h1>Article 12 &#8211; Offres commerciales<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Vous \u00eates susceptible de recevoir des offres commerciales de l&rsquo;\u00e9diteur. Si vous ne le souhaitez pas, veuillez cliquer sur le lien suivant : .<\/p>\n<p>Vos donn\u00e9es sont susceptibles d\u2019\u00eatre utilis\u00e9es par les partenaires de l&rsquo;\u00e9diteur \u00e0 des fins de prospection commerciale, si vous ne le souhaitez pas, veuillez cliquer sur le lien suivant : .<\/p>\n<p>Si, lors de la consultation du site, vous acc\u00e9dez \u00e0 des donn\u00e9es \u00e0 caract\u00e8re personnel, vous devez vous abstenir de toute collecte, de toute utilisation non autoris\u00e9e et de tout acte pouvant constituer une atteinte \u00e0 la vie priv\u00e9e ou \u00e0 la r\u00e9putation des personnes. L&rsquo;\u00e9diteur d\u00e9cline toute responsabilit\u00e9 \u00e0 cet \u00e9gard.<\/p>\n<p>Les donn\u00e9es sont conserv\u00e9es et utilis\u00e9es pour une dur\u00e9e conforme \u00e0 la l\u00e9gislation en vigueur.<\/p>\n<h1>Article 13 &#8211; Cookies<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Qu\u2019est-ce qu\u2019un \u00ab cookie \u00bb ?<\/p>\n<p>Un \u00ab Cookie \u00bb ou traceur est un fichier \u00e9lectronique d\u00e9pos\u00e9 sur un terminal (ordinateur, tablette, smartphone,\u2026) et lu par exemple lors de la consultation d&rsquo;un site internet, de la lecture d&rsquo;un courrier \u00e9lectronique, de l&rsquo;installation ou de l&rsquo;utilisation d&rsquo;un logiciel ou d&rsquo;une application mobile et ce, quel que soit le type de terminal utilis\u00e9 (source : <a href=\"https:\/\/www.cnil.fr\/fr\/cookies-traceurs-que-dit-la-loi\">https:\/\/www.cnil.fr\/fr\/cookies-traceurs- que-dit-la-loi). <\/a><a href=\"https:\/\/www.cnil.fr\/fr\/cookies-traceurs-que-dit-la-loi\"><\/a><\/p>\n<p>Le site peut collecter automatiquement des informations standards. Toutes les informations collect\u00e9es indirectement ne seront utilis\u00e9es que pour suivre le volume, le type et la configuration du trafic utilisant ce site, pour en d\u00e9velopper la conception et l&rsquo;agencement et \u00e0 d&rsquo;autres fins administratives et de planification et plus g\u00e9n\u00e9ralement pour am\u00e9liorer le service que nous vous offrons.<\/p>\n<p>Le cas \u00e9ch\u00e9ant, des \u00ab cookies \u00bb \u00e9manant de l&rsquo;\u00e9diteur du site et\/ou des soci\u00e9t\u00e9s tiers pourront \u00eatre d\u00e9pos\u00e9s sur votre terminal, avec votre accord. Dans ce cas, lors de la premi\u00e8re navigation sur ce site, une banni\u00e8re explicative sur l\u2019utilisation des \u00ab cookies \u00bb appara\u00eetra. Avant de poursuivre la navigation, le client et\/ou le prospect devra accepter ou refuser l\u2019utilisation desdits \u00ab cookies \u00bb. Le consentement donn\u00e9 sera valable pour une p\u00e9riode de treize (13) mois. L&rsquo;utilisateur a la possibilit\u00e9 de d\u00e9sactiver les cookies \u00e0 tout moment. L&rsquo;utilisateur a la possibilit\u00e9 de d\u00e9sactiver les cookies \u00e0 tout moment.<\/p>\n<p>Les cookies suivants sont pr\u00e9sents sur ce site :<\/p>\n<h1>Cookies Google :<\/h1>\n<ul>\n<li>&#8211; Google analytics : permet de mesurer l&rsquo;audience du site ; &#8211; Google tag manager : facilite l\u2019impl\u00e9mentation des tags sur les pages et permet de g\u00e9rer les balises Google ; &#8211; Google Adsense : r\u00e9gie publicitaire de Google utilisant les sites web ou les vid\u00e9os YouTube comme support pour ses annonces ; &#8211; Google Dynamic Remarketing : permet de vous proposer de la publicit\u00e9 dynamique en fonction des pr\u00e9c\u00e9dentes recherches ; &#8211; Google Adwords Conversion : outil de suivi des campagnes publicitaires adwords ; &#8211; DoubleClick : cookies publicitaires de Google pour diffuser des banni\u00e8res.<\/li>\n<\/ul>\n<p>La dur\u00e9e de vie de ces cookies est de treize mois.<\/p>\n<h1>Article 14 &#8211; Photographies et repr\u00e9sentation des produits<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Les photographies de produits, accompagnant leur description, ne sont pas contractuelles et n&rsquo;engagent pas l&rsquo;\u00e9diteur.<\/p>\n<h1>Article 15 &#8211; Loi applicable<\/h1>\n<p>Les pr\u00e9sentes conditions d&rsquo;utilisation du site sont r\u00e9gies par la loi fran\u00e7aise et soumises \u00e0 la comp\u00e9tence des tribunaux du si\u00e8ge social de l&rsquo;\u00e9diteur, sous r\u00e9serve d&rsquo;une attribution de comp\u00e9tence sp\u00e9cifique d\u00e9coulant d&rsquo;un texte de loi ou r\u00e9glementaire particulier.<\/p>\n<h1>Article 16 &#8211; Contactez-nous<\/h1>\n<p><strong> <\/strong><\/p>\n<p>Pour toute question, information sur les produits pr\u00e9sent\u00e9s sur le site, ou concernant le site lui- m\u00eame, vous pouvez laisser un message \u00e0 l&rsquo;adresse suivante : jesuschurch@live.com.<a href=\"mailto:jesuschurch@live.com\"><\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mentions l\u00e9gales et politique de confidentialit\u00e9 L&rsquo;association Jesus Church Mission Mark 16, soucieuse des droits des individus, notamment au regard des traitements automatis\u00e9s et dans une volont\u00e9 de transparence avec ses clients, a mis en place une politique reprenant l\u2019ensemble de ces traitements, des finalit\u00e9s poursuivies par ces derniers ainsi que des moyens d\u2019actions \u00e0&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-990156","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/pages\/990156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/comments?post=990156"}],"version-history":[{"count":0,"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/pages\/990156\/revisions"}],"wp:attachment":[{"href":"https:\/\/jcmm16.org\/fr\/wp-json\/wp\/v2\/media?parent=990156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}